{"id":171,"date":"2016-10-30T12:40:41","date_gmt":"2016-10-30T12:40:41","guid":{"rendered":"https:\/\/oceanwp.org\/travel\/?page_id=171"},"modified":"2025-08-18T10:46:51","modified_gmt":"2025-08-18T13:46:51","slug":"consultoria-people-analytics","status":"publish","type":"page","link":"https:\/\/www.grupowgi.com.br\/blog\/","title":{"rendered":"Blog &#8211; Consultoria People Analytics"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"171\" class=\"elementor elementor-171\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3505510d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3505510d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ebd5f5e\" data-id=\"5ebd5f5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-565c006 elementor--h-position-center elementor--v-position-middle elementor-arrows-position-inside elementor-pagination-position-inside elementor-widget elementor-widget-slides\" data-id=\"565c006\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;transition&quot;:&quot;slide&quot;,&quot;transition_speed&quot;:500}\" data-widget_type=\"slides.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper\">\n\t\t\t\t\t<div class=\"elementor-slides-wrapper elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\" dir=\"ltr\" data-animation=\"fadeInUp\">\n\t\t\t\t<div class=\"swiper-wrapper elementor-slides\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-repeater-item-8cd3f23 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.grupowgi.com.br\/blog\/o-que-e-prototipagem-de-metricas-em-analytics\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">O que \u00e9 Prototipagem de M\u00e9tricas<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Leia Mais<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-29ae19e swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.grupowgi.com.br\/blog\/a-area-de-rh-ganha-cada-vez-mais-importancia-nas-empresas\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">A \u00e1rea de RH ganha cada vez mais import\u00e2ncia nas empresas<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Leia Mais<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-04cbb34 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.grupowgi.com.br\/blog\/o-que-e-onboarding-de-colaboradores\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">O que \u00e9 onboarding de colaboradores?<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Leia Mais<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-64c26d7 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.grupowgi.com.br\/blog\/trilha-da-saude\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">A Preven\u00e7\u00e3o come\u00e7a com a informa\u00e7\u00e3o<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Assista os V\u00eddeos<\/div><\/div><\/a><\/div><div class=\"elementor-repeater-item-4db5373 swiper-slide\" role=\"group\" aria-roledescription=\"slide\"><div class=\"swiper-slide-bg\"><\/div><a class=\"swiper-slide-inner\" href=\"https:\/\/www.grupowgi.com.br\/blog\/casos-de-sucesso-de-people-analytics\/\"><div class=\"swiper-slide-contents\"><div class=\"elementor-slide-heading\">Casos de Sucesso People Analytics<\/div><div  class=\"elementor-button elementor-slide-button elementor-size-sm\">Leia Mais<\/div><\/div><\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Slide anterior\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00f3ximo slide\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cce4daf elementor-widget elementor-widget-spacer\" data-id=\"cce4daf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4067e32 elementor-widget elementor-widget-heading\" data-id=\"4067e32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Blog<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9f76d6 elementor-widget elementor-widget-spacer\" data-id=\"a9f76d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17573fde elementor-widget-tablet__width-initial elementor-grid-3 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-card-shadow-yes elementor-posts__hover-gradient load-more-align-center elementor-widget elementor-widget-posts\" data-id=\"17573fde\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;pagination_type&quot;:&quot;load_more_on_click&quot;,&quot;cards_columns&quot;:&quot;3&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;load_more_spinner&quot;:{&quot;value&quot;:&quot;fas fa-spinner&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2619 post type-post status-publish format-standard has-post-thumbnail hentry category-people-analytics entry has-media\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.grupowgi.com.br\/blog\/serie-radar-people-analytics-2025-turnover-na-industria-de-alimentos-bebidas\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/11\/Radar-People-Analytics-Alimentos-e-Bebidas-1.png\" class=\"attachment-full size-full wp-image-2618\" alt=\"\" srcset=\"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/11\/Radar-People-Analytics-Alimentos-e-Bebidas-1.png 1200w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/11\/Radar-People-Analytics-Alimentos-e-Bebidas-1-300x300.png 300w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/11\/Radar-People-Analytics-Alimentos-e-Bebidas-1-1024x1024.png 1024w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/11\/Radar-People-Analytics-Alimentos-e-Bebidas-1-150x150.png 150w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/11\/Radar-People-Analytics-Alimentos-e-Bebidas-1-768x768.png 768w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/11\/Radar-People-Analytics-Alimentos-e-Bebidas-1-600x600.png 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">People Analytics<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.grupowgi.com.br\/blog\/serie-radar-people-analytics-2025-turnover-na-industria-de-alimentos-bebidas\/\" >\n\t\t\t\tS\u00c9RIE: Radar People Analytics 2025 \u2014 Turnover na Ind\u00fastria de Alimentos &#038; Bebidas\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Hoje, o Radar People Analytics destaca o Turnover na Ind\u00fastria de Alimentos &amp; Bebidas, um segmento historicamente marcado por alta din\u00e2mica operacional, forte sazonalidade e desafios consistentes de reten\u00e7\u00e3o. Nosso prop\u00f3sito \u00e9 apoiar empresas na leitura estrat\u00e9gica dos seus indicadores de pessoas, comparando suas m\u00e9tricas internas com dados reais do<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.grupowgi.com.br\/blog\/serie-radar-people-analytics-2025-turnover-na-industria-de-alimentos-bebidas\/\" aria-label=\"Leia mais sobre S\u00c9RIE: Radar People Analytics 2025 \u2014 Turnover na Ind\u00fastria de Alimentos &#038; Bebidas\" tabindex=\"-1\" >\n\t\t\tLeia Mais \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2611 post type-post status-publish format-standard has-post-thumbnail hentry category-people-analytics entry has-media\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.grupowgi.com.br\/blog\/radar-people-analytics-diversidade-por-setor-farmaceutico\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1080\" height=\"1350\" src=\"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/11\/diversidade-farmaceutica.png\" class=\"attachment-full size-full wp-image-2610\" alt=\"\" srcset=\"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/11\/diversidade-farmaceutica.png 1080w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/11\/diversidade-farmaceutica-240x300.png 240w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/11\/diversidade-farmaceutica-819x1024.png 819w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/11\/diversidade-farmaceutica-768x960.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">People Analytics<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.grupowgi.com.br\/blog\/radar-people-analytics-diversidade-por-setor-farmaceutico\/\" >\n\t\t\t\tRadar People Analytics \u2014 Diversidade por Setor &#8211; Farmac\u00eautico\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\ud83c\udfaf S\u00c9RIE: Radar People Analytics \u2014 Diversidade por Setor &#8211; Farmac\u00eautico Nosso objetivo \u00e9 ajudar empresas a enxergarem a diversidade como estrat\u00e9gia, comparando seus pr\u00f3prios indicadores com os dados reais do mercado brasileiro. A equipe da WGI RH Tec. analisou bases p\u00fablicas do governo \u2014 CAGED e RAIS (MTE) \u2014<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.grupowgi.com.br\/blog\/radar-people-analytics-diversidade-por-setor-farmaceutico\/\" aria-label=\"Leia mais sobre Radar People Analytics \u2014 Diversidade por Setor &#8211; Farmac\u00eautico\" tabindex=\"-1\" >\n\t\t\tLeia Mais \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2606 post type-post status-publish format-standard has-post-thumbnail hentry category-people-analytics entry has-media\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.grupowgi.com.br\/blog\/diversidade-por-setor-industria-metalurgica-maquinas\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"1080\" height=\"1350\" src=\"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/Radar-People-Analytics-Edicao-Outubro-2025.png\" class=\"attachment-full size-full wp-image-2605\" alt=\"\" srcset=\"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/Radar-People-Analytics-Edicao-Outubro-2025.png 1080w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/Radar-People-Analytics-Edicao-Outubro-2025-240x300.png 240w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/Radar-People-Analytics-Edicao-Outubro-2025-819x1024.png 819w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/Radar-People-Analytics-Edicao-Outubro-2025-768x960.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">People Analytics<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.grupowgi.com.br\/blog\/diversidade-por-setor-industria-metalurgica-maquinas\/\" >\n\t\t\t\tDiversidade por Setor &#8211; Ind\u00fastria Metal\u00fargica &#038; M\u00e1quinas\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>\ud83c\udfaf S\u00c9RIE: Radar People Analytics \u2014 Ind\u00fastria Metal\u00fargica &amp; M\u00e1quinas &#8211; Edi\u00e7\u00e3o de Outubro\/2025 Nosso objetivo \u00e9 ajudar empresas a enxergarem a diversidade de forma estrat\u00e9gica, comparando seus pr\u00f3prios indicadores com os dados reais do mercado brasileiro. A equipe da WGI RH Tec. analisou bases p\u00fablicas do governo \u2014 CAGED<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.grupowgi.com.br\/blog\/diversidade-por-setor-industria-metalurgica-maquinas\/\" aria-label=\"Leia mais sobre Diversidade por Setor &#8211; Ind\u00fastria Metal\u00fargica &#038; M\u00e1quinas\" tabindex=\"-1\" >\n\t\t\tLeia Mais \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2602 post type-post status-publish format-standard has-post-thumbnail hentry category-people-analytics entry has-media\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.grupowgi.com.br\/blog\/o-que-e-ytd-e-por-que-essa-metrica-importa-para-o-rh-data-driven\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1350\" src=\"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/3-O-QUE-YTD.png\" class=\"attachment-full size-full wp-image-2601\" alt=\"\" srcset=\"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/3-O-QUE-YTD.png 1080w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/3-O-QUE-YTD-240x300.png 240w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/3-O-QUE-YTD-819x1024.png 819w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/3-O-QUE-YTD-768x960.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">People Analytics<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.grupowgi.com.br\/blog\/o-que-e-ytd-e-por-que-essa-metrica-importa-para-o-rh-data-driven\/\" >\n\t\t\t\tO que \u00e9 YTD e por que essa m\u00e9trica importa para o RH Data-Driven\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>YTD (Year-to-Date) significa \u201cdo in\u00edcio do ano at\u00e9 a data atual\u201d. \u00c9 uma m\u00e9trica simples, mas poderosa, usada para medir o desempenho acumulado de uma empresa, indicador ou investimento desde o primeiro dia do ano at\u00e9 hoje. No contexto de People Analytics, entender o YTD ajuda o RH a acompanhar<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.grupowgi.com.br\/blog\/o-que-e-ytd-e-por-que-essa-metrica-importa-para-o-rh-data-driven\/\" aria-label=\"Leia mais sobre O que \u00e9 YTD e por que essa m\u00e9trica importa para o RH Data-Driven\" tabindex=\"-1\" >\n\t\t\tLeia Mais \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2597 post type-post status-publish format-standard has-post-thumbnail hentry category-people-analytics entry has-media\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.grupowgi.com.br\/blog\/o-que-e-hr-analytics-como-os-dados-estao-transformando-a-gestao-de-pessoas\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1350\" src=\"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/33-o-que-e-hr-analytics.png\" class=\"attachment-full size-full wp-image-2596\" alt=\"\" srcset=\"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/33-o-que-e-hr-analytics.png 1080w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/33-o-que-e-hr-analytics-240x300.png 240w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/33-o-que-e-hr-analytics-819x1024.png 819w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/33-o-que-e-hr-analytics-768x960.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">People Analytics<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.grupowgi.com.br\/blog\/o-que-e-hr-analytics-como-os-dados-estao-transformando-a-gestao-de-pessoas\/\" >\n\t\t\t\tO que \u00e9 HR Analytics? Como os dados est\u00e3o transformando a gest\u00e3o de pessoas\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Introdu\u00e7\u00e3o Em um mundo empresarial cada vez mais orientado por dados, a \u00e1rea de Recursos Humanos n\u00e3o poderia ficar de fora. A pr\u00e1tica de People Analytics (tamb\u00e9m chamada de HR\u202fAnalytics) vem ganhando destaque por impulsionar a tomada de decis\u00f5es estrat\u00e9gicas em gest\u00e3o de pessoas. Neste artigo da WGI\u202fRH\u202f Tec. ,<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.grupowgi.com.br\/blog\/o-que-e-hr-analytics-como-os-dados-estao-transformando-a-gestao-de-pessoas\/\" aria-label=\"Leia mais sobre O que \u00e9 HR Analytics? Como os dados est\u00e3o transformando a gest\u00e3o de pessoas\" tabindex=\"-1\" >\n\t\t\tLeia Mais \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2592 post type-post status-publish format-standard has-post-thumbnail hentry category-people-analytics entry has-media\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/www.grupowgi.com.br\/blog\/absenteismo-um-sinal-de-alerta-para-o-rh\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1350\" src=\"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/9-o-que-e-absenteismo.png\" class=\"attachment-full size-full wp-image-2591\" alt=\"\" srcset=\"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/9-o-que-e-absenteismo.png 1080w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/9-o-que-e-absenteismo-240x300.png 240w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/9-o-que-e-absenteismo-819x1024.png 819w, https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2025\/10\/9-o-que-e-absenteismo-768x960.png 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">People Analytics<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/www.grupowgi.com.br\/blog\/absenteismo-um-sinal-de-alerta-para-o-rh\/\" >\n\t\t\t\tAbsente\u00edsmo: um sinal de alerta para o RH\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Por que o Absente\u00edsmo vai muito al\u00e9m de simples faltas? O absente\u00edsmo representa a aus\u00eancia recorrente dos colaboradores \u2014 seja por motivos justificados ou n\u00e3o \u2014 e pode ser o reflexo de problemas mais profundos dentro da organiza\u00e7\u00e3o. Para o RH moderno, ele n\u00e3o pode ser tratado apenas como um<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/www.grupowgi.com.br\/blog\/absenteismo-um-sinal-de-alerta-para-o-rh\/\" aria-label=\"Leia mais sobre Absente\u00edsmo: um sinal de alerta para o RH\" tabindex=\"-1\" >\n\t\t\tLeia Mais \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\t\t\t<span class=\"e-load-more-spinner\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-spinner\"><\/i>\t\t\t<\/span>\n\t\t\n\t\t\t\t<div class=\"e-load-more-anchor\" data-page=\"1\" data-max-page=\"10\" data-next-page=\"https:\/\/www.grupowgi.com.br\/blog\/wp-json\/wp\/v2\/pages\/171\/page\/2\/\"><\/div>\n\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Carregar mais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"e-load-more-message\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>O que \u00e9 Prototipagem de M\u00e9tricasLeia MaisA \u00e1rea de RH ganha cada vez mais import\u00e2ncia nas empresasLeia MaisO que \u00e9 onboarding de colaboradores?Leia MaisA Preven\u00e7\u00e3o come\u00e7a com a informa\u00e7\u00e3oAssista os V\u00eddeosCasos de Sucesso People AnalyticsLeia Mais Blog<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"full-screen","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"on","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","footnotes":""},"class_list":["post-171","page","type-page","status-publish","hentry","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WGI RH Tec. - Blog - Consultoria People Analytics<\/title>\n<meta name=\"description\" content=\"Consultoria People Analytics para RH. Decis\u00f5es baseadas em dados para melhorar produtividade e engajamento. Aplique insights baseados em dados para elevar a produtividade e fortalecer o engajamento da equipe. Transforme sua gest\u00e3o de talentos da sua empresa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grupowgi.com.br\/blog\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WGI RH Tec. - Blog - Consultoria People Analytics\" \/>\n<meta property=\"og:description\" content=\"Consultoria People Analytics para RH. Decis\u00f5es baseadas em dados para melhorar produtividade e engajamento. Aplique insights baseados em dados para elevar a produtividade e fortalecer o engajamento da equipe. Transforme sua gest\u00e3o de talentos da sua empresa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grupowgi.com.br\/blog\/\" \/>\n<meta property=\"og:site_name\" content=\"WGI RH Tec.\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-18T13:46:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.grupowgi.com.br\/blog\/\",\"url\":\"https:\/\/www.grupowgi.com.br\/blog\/\",\"name\":\"WGI RH Tec. - Blog - Consultoria People Analytics\",\"isPartOf\":{\"@id\":\"https:\/\/www.grupowgi.com.br\/blog\/#website\"},\"datePublished\":\"2016-10-30T12:40:41+00:00\",\"dateModified\":\"2025-08-18T13:46:51+00:00\",\"description\":\"Consultoria People Analytics para RH. Decis\u00f5es baseadas em dados para melhorar produtividade e engajamento. Aplique insights baseados em dados para elevar a produtividade e fortalecer o engajamento da equipe. Transforme sua gest\u00e3o de talentos da sua empresa.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.grupowgi.com.br\/blog\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.grupowgi.com.br\/blog\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.grupowgi.com.br\/blog\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.grupowgi.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog &#8211; Consultoria People Analytics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.grupowgi.com.br\/blog\/#website\",\"url\":\"https:\/\/www.grupowgi.com.br\/blog\/\",\"name\":\"WGI RH TEC.\",\"description\":\"Consultoria Especializada em People Analytics\",\"publisher\":{\"@id\":\"https:\/\/www.grupowgi.com.br\/blog\/#organization\"},\"alternateName\":\"WGI RH TEC. Consultoria Especializada em People Analytics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.grupowgi.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.grupowgi.com.br\/blog\/#organization\",\"name\":\"WGI RH TEC.\",\"alternateName\":\"WGI RH TEC. Consultoria Especializada em People Analytics\",\"url\":\"https:\/\/www.grupowgi.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.grupowgi.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2022\/07\/logo_wgi_150x36px.png\",\"contentUrl\":\"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2022\/07\/logo_wgi_150x36px.png\",\"width\":626,\"height\":153,\"caption\":\"WGI RH TEC.\"},\"image\":{\"@id\":\"https:\/\/www.grupowgi.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WGI RH Tec. - Blog - Consultoria People Analytics","description":"Consultoria People Analytics para RH. Decis\u00f5es baseadas em dados para melhorar produtividade e engajamento. Aplique insights baseados em dados para elevar a produtividade e fortalecer o engajamento da equipe. Transforme sua gest\u00e3o de talentos da sua empresa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grupowgi.com.br\/blog\/","og_locale":"pt_BR","og_type":"article","og_title":"WGI RH Tec. - Blog - Consultoria People Analytics","og_description":"Consultoria People Analytics para RH. Decis\u00f5es baseadas em dados para melhorar produtividade e engajamento. Aplique insights baseados em dados para elevar a produtividade e fortalecer o engajamento da equipe. Transforme sua gest\u00e3o de talentos da sua empresa.","og_url":"https:\/\/www.grupowgi.com.br\/blog\/","og_site_name":"WGI RH Tec.","article_modified_time":"2025-08-18T13:46:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.grupowgi.com.br\/blog\/","url":"https:\/\/www.grupowgi.com.br\/blog\/","name":"WGI RH Tec. - Blog - Consultoria People Analytics","isPartOf":{"@id":"https:\/\/www.grupowgi.com.br\/blog\/#website"},"datePublished":"2016-10-30T12:40:41+00:00","dateModified":"2025-08-18T13:46:51+00:00","description":"Consultoria People Analytics para RH. Decis\u00f5es baseadas em dados para melhorar produtividade e engajamento. Aplique insights baseados em dados para elevar a produtividade e fortalecer o engajamento da equipe. Transforme sua gest\u00e3o de talentos da sua empresa.","breadcrumb":{"@id":"https:\/\/www.grupowgi.com.br\/blog\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grupowgi.com.br\/blog\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.grupowgi.com.br\/blog\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.grupowgi.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Blog &#8211; Consultoria People Analytics"}]},{"@type":"WebSite","@id":"https:\/\/www.grupowgi.com.br\/blog\/#website","url":"https:\/\/www.grupowgi.com.br\/blog\/","name":"WGI RH TEC.","description":"Consultoria Especializada em People Analytics","publisher":{"@id":"https:\/\/www.grupowgi.com.br\/blog\/#organization"},"alternateName":"WGI RH TEC. Consultoria Especializada em People Analytics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grupowgi.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.grupowgi.com.br\/blog\/#organization","name":"WGI RH TEC.","alternateName":"WGI RH TEC. Consultoria Especializada em People Analytics","url":"https:\/\/www.grupowgi.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.grupowgi.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2022\/07\/logo_wgi_150x36px.png","contentUrl":"https:\/\/www.grupowgi.com.br\/blog\/wp-content\/uploads\/2022\/07\/logo_wgi_150x36px.png","width":626,"height":153,"caption":"WGI RH TEC."},"image":{"@id":"https:\/\/www.grupowgi.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.grupowgi.com.br\/blog\/wp-json\/wp\/v2\/pages\/171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.grupowgi.com.br\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.grupowgi.com.br\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.grupowgi.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grupowgi.com.br\/blog\/wp-json\/wp\/v2\/comments?post=171"}],"version-history":[{"count":577,"href":"https:\/\/www.grupowgi.com.br\/blog\/wp-json\/wp\/v2\/pages\/171\/revisions"}],"predecessor-version":[{"id":2554,"href":"https:\/\/www.grupowgi.com.br\/blog\/wp-json\/wp\/v2\/pages\/171\/revisions\/2554"}],"wp:attachment":[{"href":"https:\/\/www.grupowgi.com.br\/blog\/wp-json\/wp\/v2\/media?parent=171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}